{"id":23531,"date":"2021-09-13T08:11:00","date_gmt":"2021-09-13T06:11:00","guid":{"rendered":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx-no-6182\/"},"modified":"2023-11-13T10:42:55","modified_gmt":"2023-11-13T09:42:55","slug":"codigo-taric-para-scip-imds-cdx-no-6182","status":"publish","type":"page","link":"https:\/\/www.imds-professional.com\/es\/codigo-taric-para-scip-imds-cdx-no-6182\/","title":{"rendered":"C\u00f3digo TARIC para SCIP, IMDS, CDX (n\u00ba 6182)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"23531\" class=\"elementor elementor-23531 elementor-12175\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3251446e elementor-section-height-min-height elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3251446e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7591df1c\" data-id=\"7591df1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e3bc1be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e3bc1be\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-759d860\" data-id=\"759d860\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9aad086 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9aad086\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.imds-professional.com\/es\/formaciones-actuales\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"dticon dticon-arrow-down-outline\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver a la formaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15489b5 elementor-widget elementor-widget-heading\" data-id=\"15489b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros <b>temas de formaci\u00f3n<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b71f2e2 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"b71f2e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-599c3ab elementor-widget elementor-widget-heading\" data-id=\"599c3ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C\u00f3digo TARIC para SCIP, IMDS, CDX <b>(No. 6182)<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed2220 elementor-widget elementor-widget-text-editor\" data-id=\"5ed2220\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Objetivo de aprendizaje<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c71b22c elementor-widget elementor-widget-text-editor\" data-id=\"c71b22c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conoce el EZT Online (Arancel Aduanero Electr\u00f3nico) y la estructura del c\u00f3digo TARIC y puede clasificar sus mercanc\u00edas seg\u00fan el arancel aduanero. Conocer\u00e1 las ayudas para la agrupaci\u00f3n a partir de ejemplos y podr\u00e1 realizar su propia clasificaci\u00f3n de productos para la creaci\u00f3n del expediente SCIP.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-184eebc elementor-align-left elementor-widget elementor-widget-button\" data-id=\"184eebc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY1NTAsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sus ventajas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-320991f5 elementor-invisible\" data-id=\"320991f5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84bcedd elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"84bcedd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2618\" height=\"3039\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange.png\" class=\"attachment-full size-full wp-image-15503\" alt=\"imds-logo, Blatt, orange ,Crear el expediente SCIP ES, Requisitos actuales de REACH, Comprender Reglamento POP UE, Comprender requisitos actuales PFAS, Comprensi\u00f3n y Directiva RoHS, la industria del autom\u00f3vil, California Proposition 65, REACH en industria automotriz, Eficaz uso del CDX, CDX - Inicio r\u00e1pido, El gestor CMD en CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange.png 2618w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-258x300.png 258w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-882x1024.png 882w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-768x892.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-1323x1536.png 1323w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-1764x2048.png 1764w\" sizes=\"(max-width: 2618px) 100vw, 2618px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66589872 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66589872\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-70660c36 elementor-invisible\" data-id=\"70660c36\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d533ca9 elementor-widget elementor-widget-text-editor\" data-id=\"d533ca9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Grupo objetivo<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb60ba0 elementor-widget elementor-widget-text-editor\" data-id=\"fb60ba0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La formaci\u00f3n est\u00e1 dirigida a todos aquellos que quieran crear expedientes SCIP y necesiten clasificar sus productos individuales en un sistema de c\u00f3digos TARIC para ello.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1771b797 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1771b797\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7af4e4f0\" data-id=\"7af4e4f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e9f39e elementor-widget elementor-widget-text-editor\" data-id=\"5e9f39e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Descargar la descripci\u00f3n del curso<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2d84e8 elementor-widget elementor-widget-text-editor\" data-id=\"f2d84e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/K6182_2021_es.pdf\">C\u00f3digo TARIC para SCIP, IMDS, CDX (No.6182)<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63a5de83\" data-id=\"63a5de83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ff812ed elementor-widget elementor-widget-image\" data-id=\"6ff812ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/K6182_2021_es.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"298\" height=\"306\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/Screenshot-pdf.png\" class=\"elementor-animation-float attachment-full size-full wp-image-19900\" alt=\"PDF-Icon\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/Screenshot-pdf.png 298w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/Screenshot-pdf-292x300.png 292w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aad2d7d elementor-widget elementor-widget-text-editor\" data-id=\"4aad2d7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Fechas de formaci\u00f3n actuales<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b36f150 elementor-widget elementor-widget-wp-widget-em_widget\" data-id=\"b36f150\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-em_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"em em-list-widget em-events-widget\"><li>Keine Veranstaltungen<\/li><li class=\"all-events-link\"><a href=\"https:\/\/www.imds-professional.com\/es\/buscar-eventos\/\" title=\"alle Veranstaltungen\">alle Veranstaltungen<\/a><\/li><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5aa3cbcf elementor-invisible\" data-id=\"5aa3cbcf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2458218e elementor-widget elementor-widget-text-editor\" data-id=\"2458218e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Requisitos<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c8867d0 elementor-widget__width-initial elementor-mobile-align-start elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6c8867d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.imds-professional.com\/es\/comprobacion-del-sistema\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">En el caso de los cursos de formaci\u00f3n en l\u00ednea, se debe realizar una comprobaci\u00f3n del sistema con antelaci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Conocimientos b\u00e1sicos de IMDS, CDX o SCIP<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a422e53 elementor-widget elementor-widget-text-editor\" data-id=\"a422e53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Puede consultar el precio en los <a href=\"https:\/\/www.imds-professional.com\/es\/formaciones-actuales\/\" target=\"_blank\" rel=\"noopener\">cursos de formaci\u00f3n actuales<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c01c9 elementor-widget elementor-widget-text-editor\" data-id=\"a3c01c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Seminario exclusivo<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47266f5 elementor-widget elementor-widget-text-editor\" data-id=\"47266f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tambi\u00e9n puede reservar este seminario en exclusiva.<\/p>\n<p>Su ventaja: usted determina el lugar, la fecha y el n\u00famero de participantes y puede establecer el enfoque del contenido. Si lo desea, podemos encargarnos de toda la organizaci\u00f3n.<\/p>\n<p>\u00a1Solicite su oferta personal!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfae983 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"dfae983\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY1MzYsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Formulario de contacto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed21ba2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed21ba2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e2155b7\" data-id=\"7e2155b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef1087e elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"ef1087e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-3969904 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Recomendaciones del seminario<\/div><div class=\"elementor-slide-description\"><p>SCIP-Datenbank und Berichterstattungspflichten (No. 6180)<\/p>\n<\/div><a href=\"https:\/\/www.imds-professional.com\/es\/scip-datenbank-und-berichterstattungspflichten-no-6180\/\" class=\"elementor-button elementor-slide-button elementor-size-md\">Detalles del curso<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-93c419e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Recomendaciones del seminario<\/div><div class=\"elementor-slide-description\"><p>SCIP-Datenbank in der Praxis (No. 6181)<\/p>\n<\/div><a href=\"https:\/\/www.imds-professional.com\/es\/scip-datenbank-in-der-praxis-no-6181\/\" class=\"elementor-button elementor-slide-button elementor-size-md\">Detalles del curso<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-8790f1f swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Recomendaciones del seminario<\/div><div class=\"elementor-slide-description\"><p>CDX \u2013 Schnelleinstieg (No. 6218)<\/p>\n<\/div><a href=\"https:\/\/www.imds-professional.com\/es\/cdx-schnelleinstieg-no-6218\/\" class=\"elementor-button elementor-slide-button elementor-size-md\">Detalles del curso<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva siguiente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Volver a la formaci\u00f3n Nuestros temas de formaci\u00f3n C\u00f3digo TARIC para SCIP, IMDS, CDX (No. 6182) Objetivo de aprendizaje Conoce el EZT Online (Arancel Aduanero Electr\u00f3nico) y la estructura del c\u00f3digo TARIC y puede clasificar sus mercanc\u00edas seg\u00fan el arancel aduanero. Conocer\u00e1 las ayudas para la agrupaci\u00f3n a partir de ejemplos y podr\u00e1 realizar su [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-23531","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3digo TARIC para SCIP, IMDS, CDX<\/title>\n<meta name=\"description\" content=\"Toute personne souhaitant \u00e9tablir et d\u00e9poser un dossier SCIP a besoin du code TARIC du produit concern\u00e9. Dans cette formation, vous apprendrez comment classer vos marchandises selon le tarif douanier afin de pouvoir satisfaire \u00e0 votre obligation de notification SCIP.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3digo TARIC para SCIP, IMDS, CDX\" \/>\n<meta property=\"og:description\" content=\"Toute personne souhaitant \u00e9tablir et d\u00e9poser un dossier SCIP a besoin du code TARIC du produit concern\u00e9. Dans cette formation, vous apprendrez comment classer vos marchandises selon le tarif douanier afin de pouvoir satisfaire \u00e0 votre obligation de notification SCIP.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/\" \/>\n<meta property=\"og:site_name\" content=\"imds-professional\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T09:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange.png\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/taric-code-fuer-scip-imds-cdx\\\/\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/taric-code-fuer-scip-imds-cdx\\\/\",\"name\":\"C\u00f3digo TARIC para SCIP, IMDS, CDX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/taric-code-fuer-scip-imds-cdx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/taric-code-fuer-scip-imds-cdx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/blatt-einfarbing-orange.png\",\"datePublished\":\"2021-09-13T06:11:00+00:00\",\"dateModified\":\"2023-11-13T09:42:55+00:00\",\"description\":\"Toute personne souhaitant \u00e9tablir et d\u00e9poser un dossier SCIP a besoin du code TARIC du produit concern\u00e9. Dans cette formation, vous apprendrez comment classer vos marchandises selon le tarif douanier afin de pouvoir satisfaire \u00e0 votre obligation de notification SCIP.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/taric-code-fuer-scip-imds-cdx\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.imds-professional.com\\\/taric-code-fuer-scip-imds-cdx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/taric-code-fuer-scip-imds-cdx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/blatt-einfarbing-orange.png\",\"contentUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/blatt-einfarbing-orange.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/taric-code-fuer-scip-imds-cdx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.imds-professional.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3digo TARIC para SCIP, IMDS, CDX (n\u00ba 6182)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#website\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/\",\"name\":\"imds-professional\",\"description\":\"Demo Seite f\u00fcr ein Projekt, nicht l\u00f6schen!!! \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.imds-professional.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#organization\",\"name\":\"imds professional GmbH & Co. KG\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-TransparentHeader.png\",\"contentUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-TransparentHeader.png\",\"width\":5012,\"height\":2111,\"caption\":\"imds professional GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3digo TARIC para SCIP, IMDS, CDX","description":"Toute personne souhaitant \u00e9tablir et d\u00e9poser un dossier SCIP a besoin du code TARIC du produit concern\u00e9. Dans cette formation, vous apprendrez comment classer vos marchandises selon le tarif douanier afin de pouvoir satisfaire \u00e0 votre obligation de notification SCIP.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3digo TARIC para SCIP, IMDS, CDX","og_description":"Toute personne souhaitant \u00e9tablir et d\u00e9poser un dossier SCIP a besoin du code TARIC du produit concern\u00e9. Dans cette formation, vous apprendrez comment classer vos marchandises selon le tarif douanier afin de pouvoir satisfaire \u00e0 votre obligation de notification SCIP.","og_url":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/","og_site_name":"imds-professional","article_modified_time":"2023-11-13T09:42:55+00:00","og_image":[{"url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange.png","type":"","width":"","height":""}],"twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/","url":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/","name":"C\u00f3digo TARIC para SCIP, IMDS, CDX","isPartOf":{"@id":"https:\/\/www.imds-professional.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/#primaryimage"},"image":{"@id":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/#primaryimage"},"thumbnailUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange.png","datePublished":"2021-09-13T06:11:00+00:00","dateModified":"2023-11-13T09:42:55+00:00","description":"Toute personne souhaitant \u00e9tablir et d\u00e9poser un dossier SCIP a besoin du code TARIC du produit concern\u00e9. Dans cette formation, vous apprendrez comment classer vos marchandises selon le tarif douanier afin de pouvoir satisfaire \u00e0 votre obligation de notification SCIP.","breadcrumb":{"@id":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/#primaryimage","url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange.png","contentUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.imds-professional.com\/taric-code-fuer-scip-imds-cdx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.imds-professional.com\/en\/"},{"@type":"ListItem","position":2,"name":"C\u00f3digo TARIC para SCIP, IMDS, CDX (n\u00ba 6182)"}]},{"@type":"WebSite","@id":"https:\/\/www.imds-professional.com\/#website","url":"https:\/\/www.imds-professional.com\/","name":"imds-professional","description":"Demo Seite f\u00fcr ein Projekt, nicht l\u00f6schen!!! ","publisher":{"@id":"https:\/\/www.imds-professional.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imds-professional.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.imds-professional.com\/#organization","name":"imds professional GmbH & Co. KG","url":"https:\/\/www.imds-professional.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.imds-professional.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/06\/Logo-TransparentHeader.png","contentUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/06\/Logo-TransparentHeader.png","width":5012,"height":2111,"caption":"imds professional GmbH & Co. KG"},"image":{"@id":"https:\/\/www.imds-professional.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages\/23531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/comments?post=23531"}],"version-history":[{"count":0,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages\/23531\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/media?parent=23531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}