{"id":31759,"date":"2022-05-17T09:56:28","date_gmt":"2022-05-17T07:56:28","guid":{"rendered":"https:\/\/www.imds-professional.com\/servicio-imds-2\/"},"modified":"2024-03-13T22:05:24","modified_gmt":"2024-03-13T21:05:24","slug":"servicio-imds-2","status":"publish","type":"page","link":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/","title":{"rendered":"Servicio IMDS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"31759\" class=\"elementor elementor-31759 elementor-30527\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-310d797 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"310d797\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3806531\" data-id=\"3806531\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a86c7cb elementor-nav-menu__align-start elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"a86c7cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fa\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-a86c7cb\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-34979\"><a href=\"https:\/\/www.imds-professional.com\/imds\/\" class=\"elementor-item\">IMDS Informaci\u00f3n especializada<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-a86c7cb\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-34979\"><a href=\"https:\/\/www.imds-professional.com\/imds\/\" class=\"elementor-item\" tabindex=\"-1\">IMDS Informaci\u00f3n especializada<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1593ad0 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"1593ad0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:330,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.imds-professional.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff3192 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"2ff3192\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:440,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.imds-professional.com\/es\/formaciones-actuales\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Reserva de seminarios<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c32053f elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c32053f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:500,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.imds-professional.com\/es\/boletin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Newsletter<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e65e6da\" data-id=\"e65e6da\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7db202b elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7db202b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.imds-professional.com\/es\/temas-especializados\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"dticon dticon-arrow-down-outline\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver a los temas especializados<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7487d88 elementor-widget elementor-widget-heading\" data-id=\"7487d88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Servicio <b>IMDS<\/b><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ed5679 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"1ed5679\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c07343 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8c07343\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Asesoramiento y apoyo en materia de IMDS por parte del principal proveedor de servicios de IMDS de Europa<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddcf113 elementor-widget elementor-widget-text-editor\" data-id=\"ddcf113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">A lo largo de los a\u00f1os, nos hemos convertido en el proveedor de servicios de consultor\u00eda y apoyo del IMDS. Estamos avalados por DXC Technology, por lo que puede contar con nosotros si necesita ayuda para producir sus hojas de datos de materiales (MDS), informes de cumplimiento de sustancias qu\u00edmicas <\/span><span style=\"font-weight: 400;\">de REACH <\/span><span style=\"font-weight: 400;\">u orientaci\u00f3n sobre el sistema IMDS. Los muchos a\u00f1os que llevamos trabajando estrechamente con fabricantes, proveedores y distribuidores de la industria del autom\u00f3vil y de muchos otros sectores nos han convertido en el proveedor de servicios de IMDS elegido por muchas organizaciones de todo el mundo.<\/span><\/p><p><span style=\"font-size: 15px; font-weight: 400;\">En imds professional, abarcamos cualquier cosa que tenga que ver con el IMDS. Nuestros servicios tambi\u00e9n est\u00e1n disponibles de forma modular para adaptarse a sus necesidades. Por ejemplo, podemos encargarnos de tareas espec\u00edficas como la introducci\u00f3n de datos del IMDS, lo que le ahorrar\u00e1 dinero y le liberar\u00e1 tiempo para centrarse en los profesionales de su empresa.<\/span><\/p><p><span style=\"font-size: 15px; font-weight: 400;\">La entrada de datos del IMDS y la gesti\u00f3n de <\/span><span style=\"font-size: 15px; font-weight: 400;\">datos del IMDS <\/span><span style=\"font-size: 15px; font-weight: 400;\">requieren tiempo, conocimientos y experiencia. Tambi\u00e9n puede haber consecuencias legales para su empresa si no realiza estas tareas correctamente. Por lo tanto, es importante gestionar sus datos de IMDS de manera eficiente utilizando las soluciones y herramientas de software adecuadas. Aqu\u00ed es donde podemos intervenir y ayudarle con nuestra gama de servicios profesionales y <a href=\"https:\/\/www.imds-professional.com\/es\/ipcampus\/\">cursos de <\/a><\/span><span style=\"font-size: 15px; font-weight: 400;\"><a href=\"https:\/\/www.imds-professional.com\/es\/ipcampus\/\">formaci\u00f3n<\/a><\/span><span style=\"font-size: 15px; font-weight: 400;\">.<\/span><\/p><p><span style=\"font-size: 15px; font-weight: 400;\">Ofrecemos un asesoramiento imparcial e independiente y podemos apoyarle desde las fases iniciales de planificaci\u00f3n hasta la ejecuci\u00f3n de sus proyectos de IMDS. Tambi\u00e9n podemos ayudarle a tomar decisiones bien informadas proporcion\u00e1ndole informaci\u00f3n detallada y criterios de evaluaci\u00f3n.<\/span><\/p><p><span style=\"font-size: 15px; font-weight: 400;\">Podemos ofrecerle una soluci\u00f3n \u00fanica para todas sus necesidades, o puede elegir opciones de consultor\u00eda, formaci\u00f3n o apoyo por separado. \u00c9stas pueden proporcionarse a largo plazo o en el transcurso de un proyecto espec\u00edfico. En cualquier caso, podemos adaptar nuestras soluciones a las necesidades de su empresa. No dude en <\/span><span style=\"font-size: 15px; font-weight: 400;\">ponerse en\u00a0<\/span><a href=\"https:\/\/www.imds-professional.com\/es\/contacto\/\" target=\"_blank\" rel=\"noopener\">contacto con nosotros para concertar una consulta inicial gratuita<\/a><span style=\"font-size: 15px; font-weight: 400;\">\u00a0para hablar de sus necesidades.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fec7f49 elementor-widget elementor-widget-toggle\" data-id=\"fec7f49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2671\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2671\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">An\u00e1lisis de proyectos<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2671\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2671\"><p><span style=\"font-weight: 400;\">El an\u00e1lisis de los requisitos de su proyecto implica inicialmente la organizaci\u00f3n de una videollamada o una reuni\u00f3n in situ con usted y sus colegas para evaluar las tareas y responsabilidades espec\u00edficas del proyecto. Esto nos permite valorar si los datos del proyecto est\u00e1n completos, evaluar las listas de piezas y trazar el alcance del proyecto, los requisitos de gesti\u00f3n del proyecto, los plazos y las fechas l\u00edmite. Crearemos un plan que establezca las directrices para la comunicaci\u00f3n, la obtenci\u00f3n de informaci\u00f3n y la gesti\u00f3n de los clientes. Tambi\u00e9n definiremos procesos transparentes y especificaremos la frecuencia de los informes de estado, las directrices de entrada de datos espec\u00edficos del cliente, los procesos de aprobaci\u00f3n y la gesti\u00f3n de los proveedores.\u00a0<\/span><\/p><p><span style=\"font-size: 16px; font-weight: 400;\">Nuestro servicio de an\u00e1lisis de proyectos forma parte de nuestro paquete de consultor\u00eda. Se ha demostrado que mejora significativamente la velocidad de los procesos internos de cumplimiento de los materiales y proporciona informaci\u00f3n valiosa para garantizar que los datos de los materiales puedan gestionarse de forma profesional. Tambi\u00e9n podemos formar a sus colegas, seg\u00fan sea necesario, si prefiere implementar usted mismo sus proyectos de IMDS en la empresa.\u00a0<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2672\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2672\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Consultor\u00eda<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2672\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2672\"><span style=\"font-weight: 400;\">Podemos ayudarle a gestionar procesos como la aclaraci\u00f3n del estado del proveedor, el cambio de hitos y los plazos. Tambi\u00e9n podemos ayudarle a tratar los requisitos de los destinatarios del IMDS, la comunicaci\u00f3n con el cliente y a formular propuestas para ayudar a resolver los problemas de los proveedores. Adem\u00e1s, podemos ayudarle a establecer criterios eficaces de toma de decisiones para garantizar que su proyecto de IMDS sea todo un \u00e9xito.\u00a0<\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2673\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2673\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ejecuci\u00f3n del proyecto<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2673\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2673\"><span style=\"font-weight: 400;\">Podemos comprobar los datos y ocuparnos de todos sus requisitos de gesti\u00f3n de proveedores, introducci\u00f3n de datos y gesti\u00f3n de destinatarios del SMD. No dude en ponerse en contacto con nosotros si est\u00e1 pensando en subcontratar sus proyectos de IMDS a un proveedor de servicios profesional. Estaremos encantados de explicarle c\u00f3mo podemos ayudarle a eliminar el estr\u00e9s y los gastos de la gesti\u00f3n de los proyectos de IMDS.\u00a0<\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcac146 elementor-widget elementor-widget-spacer\" data-id=\"bcac146\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6da9eb9 elementor-widget elementor-widget-text-editor\" data-id=\"6da9eb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nuestra soluci\u00f3n integral de IMDS<\/strong><\/p>\n<p><span style=\"font-size: 16px; font-weight: 400;\">Si est\u00e1 buscando subcontratar todas sus tareas de cumplimiento de materiales, entrada de datos del IMDS y gesti\u00f3n de datos, est\u00e1 hablando con las personas adecuadas. Nuestro equipo experimentado, multidisciplinar y multiling\u00fce est\u00e1 siempre a su disposici\u00f3n para proporcionarle un apoyo r\u00e1pido y fiable. Nos aseguramos de que todos los requisitos de conformidad de los productos medioambientales se cumplan correctamente de acuerdo con la normativa. Nuestros servicios le ahorrar\u00e1n tiempo y dinero y le ayudar\u00e1n a evitar el riesgo de multas y da\u00f1os a su reputaci\u00f3n.<\/span><\/p>\n<p><a href=\"https:\/\/www.imds-professional.com\/es\/contacto\/\"><span style=\"font-size: 16px; font-weight: 400;\">No dude en <\/span><span style=\"font-size: 16px; font-weight: 400;\">ponerse en contacto con nosotros <\/span><\/a><span style=\"font-size: 16px; font-weight: 400;\"><a href=\"https:\/\/www.imds-professional.com\/es\/contacto\/\">para obtener una consulta inicial gratuita<\/a> y un presupuesto sin compromiso.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-781db21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"781db21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-49d76e0\" data-id=\"49d76e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b1d697 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"9b1d697\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-55facb3\" data-id=\"55facb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8cba3c elementor-widget elementor-widget-heading\" data-id=\"f8cba3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Convi\u00e9rtase en un <b>profesional del IMDS<\/b><br> - tipos de m\u00f3dulos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b675369 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b675369\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-052c17b\" data-id=\"052c17b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9f6593 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"f9f6593\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b3b1fa elementor-absolute elementor-widget elementor-widget-image\" data-id=\"2b3b1fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc8b37e elementor-absolute elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"bc8b37e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-385156f elementor-absolute elementor-widget elementor-widget-image\" data-id=\"385156f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8516351 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"8516351\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2da437 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"c2da437\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdd4f9e elementor-absolute elementor-widget elementor-widget-image\" data-id=\"cdd4f9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5f7994 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"c5f7994\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec00ac6 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"ec00ac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c07edf elementor-absolute elementor-widget elementor-widget-image\" data-id=\"5c07edf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-401fa35 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"401fa35\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec6d593 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"ec6d593\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f8e27 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"57f8e27\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0432b86 elementor-absolute elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0432b86\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_rotateZ_effect&quot;:&quot;yes&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_rotateZ_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_rotateZ_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"3000\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" class=\"attachment-full size-full wp-image-15475\" alt=\"IMDS data, Servicio CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png 3000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1--2048x2048.png 2048w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67ff5c1 elementor-absolute elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"67ff5c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2618\" height=\"3039\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange.png\" class=\"attachment-full size-full wp-image-15503\" alt=\"imds-logo, Blatt, orange ,Crear el expediente SCIP ES, Requisitos actuales de REACH, Comprender Reglamento POP UE, Comprender requisitos actuales PFAS, Comprensi\u00f3n y Directiva RoHS, la industria del autom\u00f3vil, California Proposition 65, REACH en industria automotriz, Eficaz uso del CDX, CDX - Inicio r\u00e1pido, El gestor CMD en CDX\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange.png 2618w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-258x300.png 258w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-882x1024.png 882w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-768x892.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-1323x1536.png 1323w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/08\/blatt-einfarbing-orange-1764x2048.png 1764w\" sizes=\"(max-width: 2618px) 100vw, 2618px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-10d094e\" data-id=\"10d094e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ece4ba elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"9ece4ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NjIsInRvZ2dsZSI6ZmFsc2V9\">Consulta inicial gratuita<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d33499b elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"d33499b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NjAsInRvZ2dsZSI6ZmFsc2V9\">Consulta introductoria<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e2006c elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"6e2006c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NTgsInRvZ2dsZSI6ZmFsc2V9\">Incorporaci\u00f3n al IMDS<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e346e74 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"e346e74\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NTYsInRvZ2dsZSI6ZmFsc2V9\">Investigaci\u00f3n de materiales<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d52a01f elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"d52a01f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NTQsInRvZ2dsZSI6ZmFsc2V9\">Comprobaci\u00f3n de datos del IMDS y SVHC<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d684e0e elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"d684e0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NTIsInRvZ2dsZSI6ZmFsc2V9\">Controles GADSL y OEM<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d55c23 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"2d55c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NTAsInRvZ2dsZSI6ZmFsc2V9\">Gesti\u00f3n de proveedores del IMDS  <\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb5e595 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"cb5e595\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NDgsInRvZ2dsZSI6ZmFsc2V9\">Apoyo a los proveedores<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffd0cf3 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"ffd0cf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NDYsInRvZ2dsZSI6ZmFsc2V9\">Gesti\u00f3n de clientes del IMDS<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e65854 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"8e65854\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NDQsInRvZ2dsZSI6ZmFsc2V9\">Listado del IMDS <\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1684d6a elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"1684d6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NDIsInRvZ2dsZSI6ZmFsc2V9\">Servicio de hoja de datos de materiales<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-282d9c7 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"282d9c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0NDAsInRvZ2dsZSI6ZmFsc2V9\">Gesti\u00f3n del proyecto IMDS<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d9280 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"e3d9280\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0MzgsInRvZ2dsZSI6ZmFsc2V9\">Soporte del software IMDS<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbd47c1 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"fbd47c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjY0MzYsInRvZ2dsZSI6ZmFsc2V9\">Fusi\u00f3n de empresas de IMDS y escisi\u00f3n de empresas<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-156c48b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"156c48b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6ee5a57\" data-id=\"6ee5a57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc19f77 elementor-widget elementor-widget-text-editor\" data-id=\"fc19f77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><b>BENEFICIOS<\/b>:<\/h3><ul><li aria-level=\"1\"><span style=\"font-weight: 400;\">Le garantizamos que sus hojas de datos de materiales ser\u00e1n aceptadas a tiempo.<\/span><\/li><\/ul><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Operamos en varios idiomas. As\u00ed, el contacto con sus clientes y proveedores de todo el mundo es m\u00e1s directo y eficaz.<\/span><\/li><\/ul><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Trabajamos estrechamente con DXC Technology y somos un socio de formaci\u00f3n autorizado de IMDS. Tambi\u00e9n actuamos en nombre del Comit\u00e9 Directivo de IMDS.<\/span><\/li><\/ul><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conocemos a fondo las <\/span><span style=\"font-weight: 400;\">directrices <\/span><span style=\"font-weight: 400;\">y recomendaciones del IMDS, as\u00ed como los <\/span><span style=\"font-weight: 400;\">requisitos <\/span><span style=\"font-weight: 400;\">espec\u00edficos <\/span><span style=\"font-weight: 400;\">de los fabricantes de autom\u00f3viles<\/span><span style=\"font-weight: 400;\">. Constituyen la base de nuestro trabajo diario y transmitimos estos conocimientos a trav\u00e9s de nuestros <\/span><span style=\"font-weight: 400;\">cursos de <a href=\"https:\/\/www.imds-professional.com\/es\/ipcampus\/\">formaci\u00f3n sobre el IMDS<\/a><\/span><span style=\"font-weight: 400;\">. Gracias a nuestras asociaciones y colaboraciones con los fabricantes de autom\u00f3viles, DXC Technology y las asociaciones de automoci\u00f3n, tenemos toda la informaci\u00f3n m\u00e1s reciente al alcance de la mano.<\/span><\/li><\/ul><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Al trabajar con nosotros, recibir\u00e1 conocimientos de primera mano y de vanguardia. Esto puede ahorrarle una gran cantidad de tiempo y esfuerzo, as\u00ed como ayudarle a evitar los costes asociados a los procedimientos de reclamaci\u00f3n y a la gesti\u00f3n de largos procesos de aclaraci\u00f3n interna.<\/span><\/li><\/ul><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Estamos orgullosos de nuestro servicio flexible, fiable y de alta calidad. Nuestros precios son competitivos y transparentes. Y adem\u00e1s, ofrecemos un servicio r\u00e1pido y amable: siempre estamos disponibles para ayudarle cuando nos necesite.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bf2a3f elementor-widget elementor-widget-text-editor\" data-id=\"6bf2a3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfLe hemos convencido de las ventajas de nuestro servicio IMDS?<\/p>\n<p><a href=\"https:\/\/www.imds-professional.com\/es\/contacto\/\" target=\"_blank\" rel=\"noopener\"><b>No dude en ponerse en contacto con nosotros para solicitar un presupuesto sin compromiso.<\/b><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>arrow-icon-size3 CONTACTO arrow-icon-size3 Reserva de seminarios arrow-icon-size3 Newsletter Volver a los temas especializados Servicio IMDS Asesoramiento y apoyo en materia de IMDS por parte del principal proveedor de servicios de IMDS de Europa A lo largo de los a\u00f1os, nos hemos convertido en el proveedor de servicios de consultor\u00eda y apoyo del IMDS. Estamos avalados [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-31759","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datos del IMDS ES<\/title>\n<meta name=\"description\" content=\"Ofrecemos asesoramiento y servicios en torno a sus datos del IMDS ES. Aproveche la oferta de una primera consulta gratuita y sin compromiso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datos del IMDS ES\" \/>\n<meta property=\"og:description\" content=\"Ofrecemos asesoramiento y servicios en torno a sus datos del IMDS ES. Aproveche la oferta de una primera consulta gratuita y sin compromiso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/\" \/>\n<meta property=\"og:site_name\" content=\"imds-professional\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-13T21:05:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/es\\\/servicio-imds-2\\\/\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/es\\\/servicio-imds-2\\\/\",\"name\":\"Datos del IMDS ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/es\\\/servicio-imds-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/es\\\/servicio-imds-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/zahnrad-fertig1-.png\",\"datePublished\":\"2022-05-17T07:56:28+00:00\",\"dateModified\":\"2024-03-13T21:05:24+00:00\",\"description\":\"Ofrecemos asesoramiento y servicios en torno a sus datos del IMDS ES. Aproveche la oferta de una primera consulta gratuita y sin compromiso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/es\\\/servicio-imds-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.imds-professional.com\\\/es\\\/servicio-imds-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/es\\\/servicio-imds-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/zahnrad-fertig1-.png\",\"contentUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/zahnrad-fertig1-.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/es\\\/servicio-imds-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.imds-professional.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicio IMDS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#website\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/\",\"name\":\"imds-professional\",\"description\":\"Demo Seite f\u00fcr ein Projekt, nicht l\u00f6schen!!! \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.imds-professional.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#organization\",\"name\":\"imds professional GmbH & Co. KG\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-TransparentHeader.png\",\"contentUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-TransparentHeader.png\",\"width\":5012,\"height\":2111,\"caption\":\"imds professional GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datos del IMDS ES","description":"Ofrecemos asesoramiento y servicios en torno a sus datos del IMDS ES. Aproveche la oferta de una primera consulta gratuita y sin compromiso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/","og_locale":"es_ES","og_type":"article","og_title":"Datos del IMDS ES","og_description":"Ofrecemos asesoramiento y servicios en torno a sus datos del IMDS ES. Aproveche la oferta de una primera consulta gratuita y sin compromiso.","og_url":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/","og_site_name":"imds-professional","article_modified_time":"2024-03-13T21:05:24+00:00","og_image":[{"url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png","type":"","width":"","height":""}],"twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/","url":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/","name":"Datos del IMDS ES","isPartOf":{"@id":"https:\/\/www.imds-professional.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/#primaryimage"},"image":{"@id":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png","datePublished":"2022-05-17T07:56:28+00:00","dateModified":"2024-03-13T21:05:24+00:00","description":"Ofrecemos asesoramiento y servicios en torno a sus datos del IMDS ES. Aproveche la oferta de una primera consulta gratuita y sin compromiso.","breadcrumb":{"@id":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/#primaryimage","url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png","contentUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/07\/zahnrad-fertig1-.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.imds-professional.com\/es\/servicio-imds-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.imds-professional.com\/en\/"},{"@type":"ListItem","position":2,"name":"Servicio IMDS"}]},{"@type":"WebSite","@id":"https:\/\/www.imds-professional.com\/#website","url":"https:\/\/www.imds-professional.com\/","name":"imds-professional","description":"Demo Seite f\u00fcr ein Projekt, nicht l\u00f6schen!!! ","publisher":{"@id":"https:\/\/www.imds-professional.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imds-professional.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.imds-professional.com\/#organization","name":"imds professional GmbH & Co. KG","url":"https:\/\/www.imds-professional.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.imds-professional.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/06\/Logo-TransparentHeader.png","contentUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/06\/Logo-TransparentHeader.png","width":5012,"height":2111,"caption":"imds professional GmbH & Co. KG"},"image":{"@id":"https:\/\/www.imds-professional.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages\/31759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/comments?post=31759"}],"version-history":[{"count":0,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages\/31759\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/media?parent=31759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}