{"id":32491,"date":"2022-06-23T10:51:36","date_gmt":"2022-06-23T08:51:36","guid":{"rendered":"https:\/\/www.imds-professional.com\/informacion-especializada-cepa\/"},"modified":"2025-02-07T10:34:29","modified_gmt":"2025-02-07T09:34:29","slug":"cepa","status":"publish","type":"page","link":"https:\/\/www.imds-professional.com\/es\/cepa\/","title":{"rendered":"CEPA &#8211; Informaci\u00f3n y servicios"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"32491\" class=\"elementor elementor-32491 elementor-32400\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-310d797 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"310d797\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3806531\" data-id=\"3806531\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a86c7cb elementor-nav-menu__align-start elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"a86c7cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fa\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-a86c7cb\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58543\"><a href=\"https:\/\/www.imds-professional.com\/es\/cepa\/\" class=\"elementor-item\">CEPA<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-a86c7cb\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-58543\"><a href=\"https:\/\/www.imds-professional.com\/es\/cepa\/\" class=\"elementor-item\" tabindex=\"-1\">CEPA<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1593ad0 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"1593ad0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:330,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.imds-professional.com\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff3192 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"2ff3192\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:440,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.imds-professional.com\/es\/formaciones-actuales\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Reserva de seminarios<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c32053f elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c32053f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:500,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.imds-professional.com\/es\/boletin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Newsletter<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e65e6da\" data-id=\"e65e6da\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7db202b elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7db202b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.imds-professional.com\/es\/temas-especializados\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"dticon dticon-arrow-down-outline\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver a los temas especializados<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7487d88 elementor-widget elementor-widget-heading\" data-id=\"7487d88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"> <b>Informaci\u00f3n y servicios sobre CEPA<\/b><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ed5679 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"1ed5679\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a4b1860 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4b1860\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f92aaad\" data-id=\"f92aaad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c07343 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8c07343\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\"Catch all\": Ley Canadiense de Protecci\u00f3n del Medio Ambiente (CEPA)<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-340c44e\" data-id=\"340c44e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9efbda elementor-widget elementor-widget-image\" data-id=\"e9efbda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280-300x199.png\" class=\"attachment-medium size-medium wp-image-57597\" alt=\"\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280-300x199.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280-1024x680.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280-768x510.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280-600x398.png 600w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280.png 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddcf113 elementor-widget elementor-widget-text-editor\" data-id=\"ddcf113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La CEPA significa \u00ab<a href=\"https:\/\/laws-lois.justice.gc.ca\/eng\/acts\/c-15.31\/\" target=\"_blank\" rel=\"noopener\">Ley canadiense de protecci\u00f3n del medio ambiente<\/a>\u00bb (en franc\u00e9s: \u00abLoi canadienne sur la protection de l&#8217;environnement\u00bb) y es una ley de protecci\u00f3n del medio ambiente en vigor en Canad\u00e1 desde 1999. Su objetivo es prevenir la contaminaci\u00f3n ambiental y tambi\u00e9n proteger la salud humana contra los riesgos de las sustancias t\u00f3xicas. La ley se aprob\u00f3 en 1988 y se revis\u00f3 en la d\u00e9cada de 1990. La nueva versi\u00f3n entr\u00f3 en vigor en 2000.<\/p><p><span style=\"font-size: 15px;\">En particular, las sustancias t\u00f3xicas persistentes (\u00abcontaminantes org\u00e1nicos persistentes\u00bb, <a href=\"https:\/\/www.imds-professional.com\/es\/reglamento-pop\/\" target=\"_blank\" rel=\"noopener\">POP<\/a>), que pueden dispersarse ampliamente en el medio ambiente, acumularse y permanecer en \u00e9l durante mucho tiempo, fueron objeto de la CEPA por primera vez en la historia de Canad\u00e1. Tambi\u00e9n se ha prestado especial atenci\u00f3n a las sustancias bioacumulables, es decir, aquellas que pueden acumularse en los organismos vivos. Algunos ejemplos de sustancias incluidas en la lista son el cromo, el cadmio, el aluminio y el formaldeh\u00eddo. El objetivo de la CEPA es eliminar por completo esas sustancias especialmente peligrosas, tambi\u00e9n para preservar los ecosistemas canadienses y la biodiversidad del pa\u00eds.<\/span><\/p><p><span style=\"font-size: 15px;\">La CEPA regula problemas de contaminaci\u00f3n que otras leyes canadienses no abordan. Proporciona la base jur\u00eddica de una serie de\u00a0<\/span><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/canadian-environmental-protection-act-registry\/monitoring-reporting-research\/monitoring.html\" target=\"_blank\" rel=\"noopener\">programas federales de protecci\u00f3n del medio ambiente y la salud<\/a><span style=\"font-size: 15px;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dee942 elementor-widget elementor-widget-toggle\" data-id=\"6dee942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1151\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1151\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfQu\u00e9 sustancias se ven afectadas?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1151\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1151\"><p>La Ley de CECoP estipula que las nuevas sustancias fabricadas o importadas en Canad\u00e1 deben ser evaluadas en cuanto a sus riesgos para la salud y el medio ambiente. La evaluaci\u00f3n de riesgos la llevan a cabo conjuntamente el Ministerio de Medio Ambiente y Cambio Clim\u00e1tico de Canad\u00e1 y el Ministerio de Sanidad de Canad\u00e1. El\u00a0<a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/managing-pollution\/evaluating-new-substances.html\" target=\"_blank\" rel=\"noopener\">Programa de Nuevas Sustancias<\/a>\u00a0administra las evaluaciones, teniendo en cuenta el\u00a0<a href=\"https:\/\/www.canada.ca\/en\/health-canada\/services\/chemical-substances\/chemicals-management-plan.html\" target=\"_blank\" rel=\"noopener\">Plan de Gesti\u00f3n de Sustancias Qu\u00edmicas (CMP)<\/a>. Se pueden buscar sustancias espec\u00edficas o grupos de sustancias en una l<a href=\"https:\/\/pollution-waste.canada.ca\/substances-search\/Substance?lang=en\" target=\"_blank\" rel=\"noopener\">ista de acceso p\u00fablico<\/a>.<\/p><p><span style=\"font-size: 16px;\">Las sustancias reguladas por la CECoP tambi\u00e9n incluyen 23.000 sustancias que pueden encontrarse en la\u00a0<\/span><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/canadian-environmental-protection-act-registry\/substances-list\/domestic.html\" target=\"_blank\" rel=\"noopener\">Lista de Sustancias Dom\u00e9sticas (DSL)<\/a><span style=\"font-size: 16px;\">, incluidas las cepas microbianas y los cultivos microbianos complejos. Se eval\u00faan tanto los organismos modificados gen\u00e9ticamente como los naturales. El\u00a0<\/span><a href=\"https:\/\/laws-lois.justice.gc.ca\/eng\/regulations\/sor-2005-248\/\" target=\"_blank\" rel=\"noopener\">Reglamento de Notificaci\u00f3n de Nuevas Sustancias (Organismos)<\/a><span style=\"font-size: 16px;\">\u00a0es decisivo para ello. En 2015, la CECoP se ampli\u00f3 para incluir un apartado sobre los nanomateriales, de modo que desde entonces tambi\u00e9n existe la obligaci\u00f3n de notificar a las autoridades canadienses las sustancias cuyas part\u00edculas tienen un tama\u00f1o de entre 1 y 100 nan\u00f3metros.<\/span><\/p><p><span style=\"font-size: 16px;\">Las sustancias clasificadas como peligrosas en el marco de la CECoP se agrupan a su vez en dos listas diferentes con distintos niveles de prioridad:<\/span><\/p><ul><li><span style=\"font-size: 16px;\">La\u00a0<\/span><a href=\"https:\/\/www.canada.ca\/en\/health-canada\/services\/environmental-workplace-health\/reports-publications\/environmental-contaminants\/first-priority-substances-list-psl1-assessments-priority-substances-assessment-program-environmental-contaminants.html\" target=\"_blank\" rel=\"noopener\">Primera Lista de Sustancias Prioritarias (PSL1)<\/a><span style=\"font-size: 16px;\">\u00a0enumeraba originalmente 44 sustancias y grupos de sustancias que son \u00abt\u00f3xicas\u00bb para la salud humana seg\u00fan el art\u00edculo 11(c) de la CEPA de 1988. Sin embargo, siete compuestos fueron retirados de la lista entre 1992 y 1994 o siguen siendo objeto de revisi\u00f3n.<\/span><\/li><li><span style=\"font-size: 16px;\">La\u00a0<\/span><a href=\"https:\/\/www.canada.ca\/en\/health-canada\/services\/environmental-workplace-health\/reports-publications\/environmental-contaminants\/second-priority-substances-list-psl2-assessments-priority-substances-assessment-program-environmental-contaminants.html\" target=\"_blank\" rel=\"noopener\">segunda lista de sustancias prioritarias (PSL2)<\/a><span style=\"font-size: 16px;\">, publicada en 1995, incluye 25 sustancias. Entre ellos se encuentran los productos qu\u00edmicos individuales, as\u00ed como las mezclas, las aguas residuales de las f\u00e1bricas textiles, las sales de la carretera y las part\u00edculas respirables con un tama\u00f1o de 10 micr\u00f3metros o menos.<\/span><\/li><\/ul><p><span style=\"font-size: 16px;\">Podemos ayudarle a mejorar la calidad de la gesti\u00f3n de los datos de los materiales y asesorarle sobre c\u00f3mo garantizar el cumplimiento de la CEPA de sus productos. Con nuestro amplio servicio y formaci\u00f3n, le ayudamos a cumplir con seguridad la normativa de la CECoP. P\u00f3ngase en <a href=\"https:\/\/www.imds-professional.com\/es\/contacto\/\">contacto <\/a>con nosotros para recibir una oferta sin compromiso.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1152\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1152\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1les son las consecuencias de infringir la ley?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1152\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1152\"><p>Si se comete una infracci\u00f3n en virtud de la Ley de CECoP, se aplica el\u00a0<a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/environmental-enforcement\/acts-regulations\/about-act\/fine-regime.html\" target=\"_blank\" rel=\"noopener\">cat\u00e1logo de multas de la Ley de Aplicaci\u00f3n de la Normativa Medioambiental (EEA)<\/a>. Se trata de una ley \u00f3mnibus sobre multas y sanciones que ha reformado y armonizado un total de nueve leyes medioambientales diferentes. La AEMA pretende conducir a una aplicaci\u00f3n m\u00e1s coherente de la legislaci\u00f3n medioambiental federal. Las sanciones monetarias administrativas en virtud de las partes 7 y 9 de la Ley de CECoP se establecen en la\u00a0<a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/environmental-enforcement\/publications\/policy-framework-administrative-penalties-act.html\" target=\"_blank\" rel=\"noopener\">Ley de Sanciones Monetarias Administrativas por Infracciones Ambientales (EVAMPA)<\/a>\u00a0y se han especificado en el\u00a0<a href=\"https:\/\/laws-lois.justice.gc.ca\/eng\/regulations\/SOR-2017-109\/\" target=\"_blank\" rel=\"noopener\">Reglamento de Sanciones Monetarias Administrativas por Infracciones Ambientales (Reglamento de AMPs)<\/a>. Seg\u00fan esta normativa, las infracciones de la CEPA est\u00e1n sujetas a determinadas multas m\u00ednimas, que se incrementan en caso de condena. Van de 5.000 a 6.000.000 de d\u00f3lares.<\/p><p><span style=\"font-size: 16px;\">Otras acciones de aplicaci\u00f3n de la normativa en materia de CECoP son, por ejemplo:<\/span><\/p><ul><li><span style=\"font-size: 16px;\">Avisos de sanci\u00f3n, por ejemplo si faltan informes escritos<\/span><\/li><li>Prohibiciones, retiradas de sustancias ilegales u \u00f3rdenes de cese de acciones ilegales o de exigencia de las legales<\/li><li>\u00d3rdenes de alejamiento<\/li><li>Acusaci\u00f3n penal por parte de la fiscal\u00eda<\/li><li>Advertencias con la oportunidad de que los presuntos infractores tomen buenas medidas de cumplimiento<\/li><li>\u00d3rdenes relativas a la liberaci\u00f3n ilegal de sustancias reguladas, que regulan espec\u00edficamente la manipulaci\u00f3n de las sustancias.<\/li><\/ul><p>Las infracciones se especifican en la Ley de CECoP y se regulan en un reglamento independiente, el\u00a0<a href=\"https:\/\/pollution-waste.canada.ca\/environmental-protection-registry\/regulations\/view?Id=113\" target=\"_blank\" rel=\"noopener\">\u00abReglamento que designa las disposiciones reglamentarias a efectos de aplicaci\u00f3n (Ley canadiense de protecci\u00f3n del medio ambiente, 1999)\u00bb<\/a>.<\/p><p><span style=\"font-size: 16px;\">Tambi\u00e9n es posible realizar una detenci\u00f3n -incluso sin orden judicial- o incautar objetos adem\u00e1s de pruebas. Incluso los buques sospechosos de haber cometido un delito pueden ser retenidos o desviados sobre la base de la Ley de CECoP y el EEE. Las condenas o incluso los cargos en el marco de la EEE pueden dar lugar a penas de prisi\u00f3n de hasta tres a\u00f1os. Los delitos perseguidos en virtud de la CECoP se publican en\u00a0<\/span><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/environmental-enforcement\/annual-reports-statistics.html\" target=\"_blank\" rel=\"noopener\">informes peri\u00f3dicos del Ministerio de Medio Ambiente canadiense<\/a><span style=\"font-size: 16px;\">.<\/span><\/p><p><span style=\"font-size: 16px;\">Para recibir las noticias pol\u00edticas m\u00e1s importantes e informaci\u00f3n t\u00e9cnica sobre la CECoP y otros temas relacionados con el cumplimiento de la normativa, simplemente suscr\u00edbase a nuestro <a href=\"https:\/\/www.imds-professional.com\/es\/boletin\/\">bolet\u00edn<\/a>.<\/span><\/p><p><span style=\"font-size: 16px;\">\u00bfTiene preguntas espec\u00edficas y necesita formaci\u00f3n o servicio? Con nuestros servicios ejecutivos y de asesoramiento, tenemos muchos servicios en nuestro programa para facilitarle el cumplimiento de la CECoP. Podemos ayudarle de forma r\u00e1pida y competente en alem\u00e1n y en muchos otros idiomas. P\u00f3ngase en contacto con nuestro equipo <a href=\"https:\/\/www.imds-professional.com\/es\/contacto\/\">aqu\u00ed<\/a>.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1153\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1153\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Enlaces \u00fatiles a la CEPA<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1153\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1153\"><table width=\"630\">\r\n<tbody>\r\n<tr>\r\n<td width=\"470\">P\u00e1gina oficial de la CEPA:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/canadian-environmental-protection-act-registry\/enforcement-compliance.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\"><span class=\"TextRun BCX0 SCXW83772578\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun BCX0 SCXW83772578\"><span style=\"font-family: inherit; font-size: inherit;\">Antecedentes y m\u00e1s informaci\u00f3n sobre la CEPA:<\/span>\r\n<\/span><\/span><\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/services\/environment\/pollution-waste-management\/understanding-environmental-protection-act.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">Texto original de la CEPA:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/laws-lois.justice.gc.ca\/eng\/acts\/c-15.31\/\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\"><span class=\"TextRun BCX0 SCXW123548458\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun BCX0 SCXW123548458\">Gu\u00eda del gobierno canadiense para entender la CEPA<\/span><\/span>:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/canadian-environmental-protection-act-registry\/publications\/guide-to-understanding.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">P\u00e1gina con una visi\u00f3n general de los programas federales de protecci\u00f3n del medio ambiente y la salud de Canad\u00e1:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/canadian-environmental-protection-act-registry\/monitoring-reporting-research\/monitoring.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\"><span class=\"TextRun SCXW96180707 BCX0\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW96180707 BCX0\">Informe de evaluaci\u00f3n de la CEPA de 2017<\/span><\/span>:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.ourcommons.ca\/DocumentViewer\/en\/42-1\/ENVI\/report-8\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">P\u00e1gina del Gobierno de Canad\u00e1 sobre el Programa de Nuevas Sustancias:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/managing-pollution\/evaluating-new-substances.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">P\u00e1gina del gobierno canadiense sobre el Plan de Gesti\u00f3n de Productos Qu\u00edmicos:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/health-canada\/services\/chemical-substances\/chemicals-management-plan.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">Para buscar en la lista de sustancias y grupos de sustancias de la CEPA (listas de sustancias):<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/canadian-environmental-protection-act-registry.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">A la Lista de Sustancias Dom\u00e9sticas (DSL):<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/canadian-environmental-protection-act-registry\/substances-list\/domestic.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">Al \u00abReglamento de Notificaci\u00f3n de Nuevas Sustancias (Organismos)\u00bb:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/laws-lois.justice.gc.ca\/eng\/regulations\/sor-2005-248\/\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">A la primera lista de sustancias prioritarias (PSL1):<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/health-canada\/services\/environmental-workplace-health\/reports-publications\/environmental-contaminants\/first-priority-substances-list-psl1-assessments-priority-substances-assessment-program-environmental-contaminants.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">A la segunda lista de sustancias prioritarias (PSL2):<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/health-canada\/services\/environmental-workplace-health\/reports-publications\/environmental-contaminants\/second-priority-substances-list-psl2-assessments-priority-substances-assessment-program-environmental-contaminants.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">Multas en virtud de la Ley de Aplicaci\u00f3n de la Normativa Medioambiental (EEA):<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/environmental-enforcement\/acts-regulations\/about-act\/fine-regime.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\"><span class=\"NormalTextRun BCX0 SCXW267363766\">A las sanciones monetarias administrativas de la Ley de Sanciones Monetarias Administrativas por Infracciones Ambientales (EVAMPA):<\/span><\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/environmental-enforcement\/publications\/policy-framework-administrative-penalties-act.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">Disposiciones sancionadoras detalladas en el \u00abReglamento de Sanciones Monetarias Administrativas por Infracciones Medioambientales (Reglamento AMPs)\u00bb:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/laws-lois.justice.gc.ca\/eng\/regulations\/SOR-2017-109\/\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">Infracciones en virtud del \u00abReglamento por el que se designan las disposiciones reglamentarias a efectos de su aplicaci\u00f3n (Ley canadiense de protecci\u00f3n del medio ambiente, 1999)\u00bb:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/pollution-waste.canada.ca\/environmental-protection-registry\/regulations\/view?Id=113\">Link<\/a><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"470\">P\u00e1gina con informes peri\u00f3dicos y estad\u00edsticas sobre la CEPA del Ministerio de Medio Ambiente de Canad\u00e1:<\/td>\r\n<td width=\"160\"><a href=\"https:\/\/www.canada.ca\/en\/environment-climate-change\/services\/environmental-enforcement\/annual-reports-statistics.html\">Link<\/a><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35db097 elementor-widget elementor-widget-image\" data-id=\"35db097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/03\/ZahnradBlatt_RGB_freigestellt-Konfliktmineralien-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-51787\" alt=\"Konfliktmineralien\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/03\/ZahnradBlatt_RGB_freigestellt-Konfliktmineralien-150x150.png 150w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/03\/ZahnradBlatt_RGB_freigestellt-Konfliktmineralien-300x300.png 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/03\/ZahnradBlatt_RGB_freigestellt-Konfliktmineralien-1024x1024.png 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/03\/ZahnradBlatt_RGB_freigestellt-Konfliktmineralien-768x768.png 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/03\/ZahnradBlatt_RGB_freigestellt-Konfliktmineralien-1536x1536.png 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/03\/ZahnradBlatt_RGB_freigestellt-Konfliktmineralien-600x600.png 600w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/03\/ZahnradBlatt_RGB_freigestellt-Konfliktmineralien-100x100.png 100w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/03\/ZahnradBlatt_RGB_freigestellt-Konfliktmineralien.png 1980w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94e650f elementor-widget elementor-widget-heading\" data-id=\"94e650f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicios relacionados con la CEPA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e43e866 elementor-widget elementor-widget-text-editor\" data-id=\"e43e866\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Podemos ayudarle a averiguar si sus productos se ven afectados por la normativa de CEPA. Aumente la calidad del cumplimiento de sus materiales con nosotros.<\/p><p>En una primera consulta gratuita, le ofrecemos una visi\u00f3n general de nuestros servicios. <a href=\"https:\/\/outlook.office365.com\/book\/imdsprofessionalinternational@imds-professional.com\/\" target=\"_blank\" rel=\"noopener\">Concierte una cita ahora.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b86af elementor-widget elementor-widget-heading\" data-id=\"77b86af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formaci\u00f3n sobre CEPA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f132a90 elementor-widget elementor-widget-text-editor\" data-id=\"f132a90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Puede inscribirse en la formaci\u00f3n sobre CEPA en nuestro <a href=\"https:\/\/www.imds-professional.com\/es\/ipcampus\/\" target=\"_blank\" rel=\"noopener\">ipCampus<\/a>. Aqu\u00ed conocer\u00e1 los objetivos y el contexto de la Ley canadiense de protecci\u00f3n del medio ambiente y recibir\u00e1 estrategias concretas de aplicaci\u00f3n. Si es necesario, podemos dise\u00f1ar un curso de formaci\u00f3n exclusivo para su empresa. No dude en ponerse en contacto con nosotros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>arrow-icon-size3 CONTACTO arrow-icon-size3 Reserva de seminarios arrow-icon-size3 Newsletter Volver a los temas especializados Informaci\u00f3n y servicios sobre CEPA \u00abCatch all\u00bb: Ley Canadiense de Protecci\u00f3n del Medio Ambiente (CEPA) La CEPA significa \u00abLey canadiense de protecci\u00f3n del medio ambiente\u00bb (en franc\u00e9s: \u00abLoi canadienne sur la protection de l&#8217;environnement\u00bb) y es una ley de protecci\u00f3n del medio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-32491","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CEPA - Informaci\u00f3n y servicios<\/title>\n<meta name=\"description\" content=\"Aqu\u00ed encontrar\u00e1 la Ley Canadiense de Protecci\u00f3n del Medio Ambiente (CEPA). Su objetivo es proteger el medio ambiente y la salud humana.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imds-professional.com\/cepa-kanada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEPA - Informaci\u00f3n y servicios\" \/>\n<meta property=\"og:description\" content=\"Aqu\u00ed encontrar\u00e1 la Ley Canadiense de Protecci\u00f3n del Medio Ambiente (CEPA). Su objetivo es proteger el medio ambiente y la salud humana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imds-professional.com\/cepa-kanada\/\" \/>\n<meta property=\"og:site_name\" content=\"imds-professional\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-07T09:34:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/cepa-kanada\\\/\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/cepa-kanada\\\/\",\"name\":\"CEPA - Informaci\u00f3n y servicios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/cepa-kanada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/cepa-kanada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/canada-159585_1280-300x199.png\",\"datePublished\":\"2022-06-23T08:51:36+00:00\",\"dateModified\":\"2025-02-07T09:34:29+00:00\",\"description\":\"Aqu\u00ed encontrar\u00e1 la Ley Canadiense de Protecci\u00f3n del Medio Ambiente (CEPA). Su objetivo es proteger el medio ambiente y la salud humana.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/cepa-kanada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.imds-professional.com\\\/cepa-kanada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/cepa-kanada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/canada-159585_1280-300x199.png\",\"contentUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/canada-159585_1280-300x199.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/cepa-kanada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.imds-professional.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CEPA &#8211; Informaci\u00f3n y servicios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#website\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/\",\"name\":\"imds-professional\",\"description\":\"Demo Seite f\u00fcr ein Projekt, nicht l\u00f6schen!!! \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.imds-professional.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#organization\",\"name\":\"imds professional GmbH & Co. KG\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-TransparentHeader.png\",\"contentUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-TransparentHeader.png\",\"width\":5012,\"height\":2111,\"caption\":\"imds professional GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CEPA - Informaci\u00f3n y servicios","description":"Aqu\u00ed encontrar\u00e1 la Ley Canadiense de Protecci\u00f3n del Medio Ambiente (CEPA). Su objetivo es proteger el medio ambiente y la salud humana.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.imds-professional.com\/cepa-kanada\/","og_locale":"es_ES","og_type":"article","og_title":"CEPA - Informaci\u00f3n y servicios","og_description":"Aqu\u00ed encontrar\u00e1 la Ley Canadiense de Protecci\u00f3n del Medio Ambiente (CEPA). Su objetivo es proteger el medio ambiente y la salud humana.","og_url":"https:\/\/www.imds-professional.com\/cepa-kanada\/","og_site_name":"imds-professional","article_modified_time":"2025-02-07T09:34:29+00:00","og_image":[{"width":1280,"height":850,"url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280.png","type":"image\/png"}],"twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.imds-professional.com\/cepa-kanada\/","url":"https:\/\/www.imds-professional.com\/cepa-kanada\/","name":"CEPA - Informaci\u00f3n y servicios","isPartOf":{"@id":"https:\/\/www.imds-professional.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.imds-professional.com\/cepa-kanada\/#primaryimage"},"image":{"@id":"https:\/\/www.imds-professional.com\/cepa-kanada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280-300x199.png","datePublished":"2022-06-23T08:51:36+00:00","dateModified":"2025-02-07T09:34:29+00:00","description":"Aqu\u00ed encontrar\u00e1 la Ley Canadiense de Protecci\u00f3n del Medio Ambiente (CEPA). Su objetivo es proteger el medio ambiente y la salud humana.","breadcrumb":{"@id":"https:\/\/www.imds-professional.com\/cepa-kanada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.imds-professional.com\/cepa-kanada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.imds-professional.com\/cepa-kanada\/#primaryimage","url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280-300x199.png","contentUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2024\/08\/canada-159585_1280-300x199.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.imds-professional.com\/cepa-kanada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.imds-professional.com\/en\/"},{"@type":"ListItem","position":2,"name":"CEPA &#8211; Informaci\u00f3n y servicios"}]},{"@type":"WebSite","@id":"https:\/\/www.imds-professional.com\/#website","url":"https:\/\/www.imds-professional.com\/","name":"imds-professional","description":"Demo Seite f\u00fcr ein Projekt, nicht l\u00f6schen!!! ","publisher":{"@id":"https:\/\/www.imds-professional.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imds-professional.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.imds-professional.com\/#organization","name":"imds professional GmbH & Co. KG","url":"https:\/\/www.imds-professional.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.imds-professional.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/06\/Logo-TransparentHeader.png","contentUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/06\/Logo-TransparentHeader.png","width":5012,"height":2111,"caption":"imds professional GmbH & Co. KG"},"image":{"@id":"https:\/\/www.imds-professional.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages\/32491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/comments?post=32491"}],"version-history":[{"count":3,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages\/32491\/revisions"}],"predecessor-version":[{"id":62739,"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/pages\/32491\/revisions\/62739"}],"wp:attachment":[{"href":"https:\/\/www.imds-professional.com\/es\/wp-json\/wp\/v2\/media?parent=32491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}