{"id":24829,"date":"2021-11-08T16:12:26","date_gmt":"2021-11-08T15:12:26","guid":{"rendered":"https:\/\/www.imds-professional.com\/argomenti-della-formazione\/"},"modified":"2024-05-08T11:49:41","modified_gmt":"2024-05-08T09:49:41","slug":"argomenti-della-formazione","status":"publish","type":"page","link":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/","title":{"rendered":"Argomenti della formazione"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"24829\" class=\"elementor elementor-24829 elementor-20993\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d730b0d elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d730b0d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c96d552\" data-id=\"c96d552\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1664f41 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"1664f41\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-06793db\" data-id=\"06793db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5db3609 elementor-widget elementor-widget-heading\" data-id=\"5db3609\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">I nostri <b>ipCampus<\/b><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aadf80 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5aadf80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe560df animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fe560df\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CORSI DI FORMAZIONE SULLA CONFORMIT\u00c0 DEI MATERIALI PROFESSIONALI<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43314a elementor-widget elementor-widget-text-editor\" data-id=\"f43314a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Clicca sugli argomenti nelle piastrelle per avere una panoramica della nostra offerta di formazione.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ef848c elementor-align-left elementor-widget elementor-widget-button\" data-id=\"0ef848c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.imds-professional.com\/aktuelle-schulungen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Alla lista con le formazioni in corso<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3667466 elementor-widget elementor-widget-spacer\" data-id=\"3667466\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d91fad4 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"d91fad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.imds-professional.com\/it\/calendrier-des-seminaires\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Calendario dei seminari<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dbf9904\" data-id=\"dbf9904\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-986c9a9 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"986c9a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"856\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1.jpg\" class=\"attachment-full size-full wp-image-15523\" alt=\"ipCampus EN, ipCampus ITA\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1.jpg 2000w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1-300x128.jpg 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1-1024x438.jpg 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1-768x329.jpg 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1-1536x657.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0397ac8 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"0397ac8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_delay&quot;:0}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"931\" src=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Tropfen1-scaled.jpg\" class=\"attachment-full size-full wp-image-15520\" alt=\"ipCampus EN, ipCampus ITA\" srcset=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Tropfen1-scaled.jpg 2560w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Tropfen1-300x109.jpg 300w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Tropfen1-1024x372.jpg 1024w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Tropfen1-768x279.jpg 768w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Tropfen1-1536x558.jpg 1536w, https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Tropfen1-2048x744.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1630b857 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1630b857\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-553b80a4\" data-id=\"553b80a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-27233c86 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"27233c86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-175efe44\" data-id=\"175efe44\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54617f5a elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"54617f5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tIMDS\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjMxMDUsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db573d6 elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"db573d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tCDX\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjMwOTUsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82caeba elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"82caeba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tBiocidi\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjMwOTcsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c2f4db5\" data-id=\"2c2f4db5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a5de77 elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"5a5de77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tCAMDS\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjMwOTEsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51e1eb9 elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"51e1eb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tROHS\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjMwOTMsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e996018 elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"e996018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tProposition<br>65\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjMwODksInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb8322d elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"bb8322d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tLegge sulla Supply Chain\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MzM1NzgsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6cbdf8a5\" data-id=\"6cbdf8a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c47f3b3 elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"c47f3b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tREACH\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjMxMDMsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7271eb7 elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"7271eb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tDatabase SCIP\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjMxMDEsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a1f31c elementor-flip-box--effect-push elementor-flip-box--direction-up elementor-widget elementor-widget-flip-box\" data-id=\"5a1f31c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\t\tMinerali di conflitto + Cobalto\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-flip-box__layer__description\">\n\t\t\t\t\t\t\t\tClicca qui\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<a class=\"elementor-flip-box__layer elementor-flip-box__back\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjMwOTksInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-flip-box__layer__title\">\n\t\t\t\t\t\t\tAi corsi di formazione\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-581795cf\" data-id=\"581795cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b3bdeb elementor-widget elementor-widget-heading\" data-id=\"0b3bdeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>Conoscenza<\/b> della conformit\u00e0 dei materiali<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74335a0 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"74335a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0ec5fd elementor-widget elementor-widget-heading\" data-id=\"d0ec5fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I nostri <br><b>ipCampus ITA argomenti di formazione<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-268ae298 elementor-widget elementor-widget-text-editor\" data-id=\"268ae298\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Impartiamo le nostre conoscenze in molte lingue e &#8211; come \u00e8 meglio per l&#8217;apprendimento: su misura per le tue esigenze, in modo che tu possa applicare subito le nuove conoscenze. Puoi contare sulla nostra decennale esperienza come fornitore di formazione in rete a livello globale. Siamo leader di mercato in Europa per IMDS e CDX e siamo autorizzati dallo sviluppatore IMDS DXC Technology. Offriamo i nostri corsi di formazione sia pubblicamente che in esclusiva. Adattiamo i corsi di formazione esclusivi individualmente alle vostre esigenze.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69f1ea6 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"69f1ea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.imds-professional.com\/it\/contatto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b385ca18-4b85-46d4-bb4b-571c73a19812\" data-name=\"b922a425-e5e0-4ef1-881c-5748460fd139\" viewBox=\"0 0 30.125 18.1738\"><title>arrow-icon-size3<\/title><path d=\"M29.75,9.3948,21.5281,1.1735a.8479.8479,0,0,0-.601-.261L20.9124.9119a.8526.8526,0,0,0-.5956.2409.8642.8642,0,0,0-.0027,1.23l6.7618,6.7611H.7316a.8566.8566,0,1,0,0,1.7131H27.0759l-6.7591,6.7591a.8576.8576,0,0,0-.0214,1.2113.8462.8462,0,0,0,.61.2583.8949.8949,0,0,0,.621-.2556l8.2233-8.224A.8587.8587,0,0,0,29.75,9.3948Z\" transform=\"translate(0.125 -0.9119)\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi una formazione esclusiva<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>I nostri ipCampus CORSI DI FORMAZIONE SULLA CONFORMIT\u00c0 DEI MATERIALI PROFESSIONALI Clicca sugli argomenti nelle piastrelle per avere una panoramica della nostra offerta di formazione. arrow-icon-size3 Alla lista con le formazioni in corso arrow-icon-size3 Calendario dei seminari IMDS Clicca qui Ai corsi di formazione CDX Clicca qui Ai corsi di formazione Biocidi Clicca qui Ai [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-24829","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ipCampus ITA | Argomenti della formazione<\/title>\n<meta name=\"description\" content=\"Nel nostro ITA ipCampus vi offriamo una gamma di argomenti specializzati e formati di apprendimento per la compatibilit\u00e0 ambientale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ipCampus ITA | Argomenti della formazione\" \/>\n<meta property=\"og:description\" content=\"Nel nostro ITA ipCampus vi offriamo una gamma di argomenti specializzati e formati di apprendimento per la compatibilit\u00e0 ambientale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/\" \/>\n<meta property=\"og:site_name\" content=\"imds-professional\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T09:49:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/it\\\/argomenti-della-formazione\\\/\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/it\\\/argomenti-della-formazione\\\/\",\"name\":\"ipCampus ITA | Argomenti della formazione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/it\\\/argomenti-della-formazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/it\\\/argomenti-della-formazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Solar1.jpg\",\"datePublished\":\"2021-11-08T15:12:26+00:00\",\"dateModified\":\"2024-05-08T09:49:41+00:00\",\"description\":\"Nel nostro ITA ipCampus vi offriamo una gamma di argomenti specializzati e formati di apprendimento per la compatibilit\u00e0 ambientale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/it\\\/argomenti-della-formazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.imds-professional.com\\\/it\\\/argomenti-della-formazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/it\\\/argomenti-della-formazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Solar1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Solar1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/it\\\/argomenti-della-formazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.imds-professional.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Argomenti della formazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#website\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/\",\"name\":\"imds-professional\",\"description\":\"Demo Seite f\u00fcr ein Projekt, nicht l\u00f6schen!!! \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.imds-professional.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#organization\",\"name\":\"imds professional GmbH & Co. KG\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-TransparentHeader.png\",\"contentUrl\":\"https:\\\/\\\/www.imds-professional.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo-TransparentHeader.png\",\"width\":5012,\"height\":2111,\"caption\":\"imds professional GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.imds-professional.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ipCampus ITA | Argomenti della formazione","description":"Nel nostro ITA ipCampus vi offriamo una gamma di argomenti specializzati e formati di apprendimento per la compatibilit\u00e0 ambientale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/","og_locale":"it_IT","og_type":"article","og_title":"ipCampus ITA | Argomenti della formazione","og_description":"Nel nostro ITA ipCampus vi offriamo una gamma di argomenti specializzati e formati di apprendimento per la compatibilit\u00e0 ambientale.","og_url":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/","og_site_name":"imds-professional","article_modified_time":"2024-05-08T09:49:41+00:00","og_image":[{"url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1.jpg","type":"","width":"","height":""}],"twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/","url":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/","name":"ipCampus ITA | Argomenti della formazione","isPartOf":{"@id":"https:\/\/www.imds-professional.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/#primaryimage"},"image":{"@id":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1.jpg","datePublished":"2021-11-08T15:12:26+00:00","dateModified":"2024-05-08T09:49:41+00:00","description":"Nel nostro ITA ipCampus vi offriamo una gamma di argomenti specializzati e formati di apprendimento per la compatibilit\u00e0 ambientale.","breadcrumb":{"@id":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/#primaryimage","url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1.jpg","contentUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/09\/Solar1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.imds-professional.com\/it\/argomenti-della-formazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.imds-professional.com\/en\/"},{"@type":"ListItem","position":2,"name":"Argomenti della formazione"}]},{"@type":"WebSite","@id":"https:\/\/www.imds-professional.com\/#website","url":"https:\/\/www.imds-professional.com\/","name":"imds-professional","description":"Demo Seite f\u00fcr ein Projekt, nicht l\u00f6schen!!! ","publisher":{"@id":"https:\/\/www.imds-professional.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.imds-professional.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.imds-professional.com\/#organization","name":"imds professional GmbH & Co. KG","url":"https:\/\/www.imds-professional.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.imds-professional.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/06\/Logo-TransparentHeader.png","contentUrl":"https:\/\/www.imds-professional.com\/wp-content\/uploads\/2021\/06\/Logo-TransparentHeader.png","width":5012,"height":2111,"caption":"imds professional GmbH & Co. KG"},"image":{"@id":"https:\/\/www.imds-professional.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.imds-professional.com\/it\/wp-json\/wp\/v2\/pages\/24829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imds-professional.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.imds-professional.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.imds-professional.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imds-professional.com\/it\/wp-json\/wp\/v2\/comments?post=24829"}],"version-history":[{"count":0,"href":"https:\/\/www.imds-professional.com\/it\/wp-json\/wp\/v2\/pages\/24829\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.imds-professional.com\/it\/wp-json\/wp\/v2\/media?parent=24829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}